{"id":9018,"date":"2019-07-08T01:03:46","date_gmt":"2019-07-07T23:03:46","guid":{"rendered":"https:\/\/ekkla.ch\/nos-services\/"},"modified":"2023-11-23T16:01:31","modified_gmt":"2023-11-23T15:01:31","slug":"unsere-dienstleistungen","status":"publish","type":"page","link":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/","title":{"rendered":"Unsere Dienstleistungen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-generic.php","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v22.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Beleuchtungsl\u00f6sungen | Beleuchtung | Ideen | Designer-Beleuchtung<\/title>\n<meta name=\"description\" content=\"Massgeschneiderte L\u00f6sungen f\u00fcr die Beleuchtung Ihres Innenraums, Raum- und Lichtanalyse, Auswahl von Trendleuchten, Beleuchtung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Dienstleistungen\" \/>\n<meta property=\"og:description\" content=\"Massgeschneiderte L\u00f6sungen f\u00fcr die Beleuchtung Ihres Innenraums, Raum- und Lichtanalyse, Auswahl von Trendleuchten, Beleuchtung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ekkla\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T15:01:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/\",\"url\":\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/\",\"name\":\"Beleuchtungsl\u00f6sungen | Beleuchtung | Ideen | Designer-Beleuchtung\",\"isPartOf\":{\"@id\":\"https:\/\/ekkla.ch\/#website\"},\"datePublished\":\"2019-07-07T23:03:46+00:00\",\"dateModified\":\"2023-11-23T15:01:31+00:00\",\"description\":\"Massgeschneiderte L\u00f6sungen f\u00fcr die Beleuchtung Ihres Innenraums, Raum- und Lichtanalyse, Auswahl von Trendleuchten, Beleuchtung\",\"breadcrumb\":{\"@id\":\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ekkla.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Dienstleistungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ekkla.ch\/#website\",\"url\":\"https:\/\/ekkla.ch\/\",\"name\":\"Ekkla\",\"description\":\"Der Onlineshop f\u00fcr Beleuchtung\",\"publisher\":{\"@id\":\"https:\/\/ekkla.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ekkla.ch\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ekkla.ch\/#organization\",\"name\":\"Ekkla\",\"url\":\"https:\/\/ekkla.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ekkla.ch\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ekkla.ch\/wp-content\/uploads\/2019\/07\/logo-1.svg\",\"contentUrl\":\"http:\/\/ekkla.ch\/wp-content\/uploads\/2019\/07\/logo-1.svg\",\"width\":1,\"height\":1,\"caption\":\"Ekkla\"},\"image\":{\"@id\":\"https:\/\/ekkla.ch\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/ekkla_light\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Beleuchtungsl\u00f6sungen | Beleuchtung | Ideen | Designer-Beleuchtung","description":"Massgeschneiderte L\u00f6sungen f\u00fcr die Beleuchtung Ihres Innenraums, Raum- und Lichtanalyse, Auswahl von Trendleuchten, Beleuchtung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere Dienstleistungen","og_description":"Massgeschneiderte L\u00f6sungen f\u00fcr die Beleuchtung Ihres Innenraums, Raum- und Lichtanalyse, Auswahl von Trendleuchten, Beleuchtung","og_url":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/","og_site_name":"Ekkla","article_modified_time":"2023-11-23T15:01:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/","url":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/","name":"Beleuchtungsl\u00f6sungen | Beleuchtung | Ideen | Designer-Beleuchtung","isPartOf":{"@id":"https:\/\/ekkla.ch\/#website"},"datePublished":"2019-07-07T23:03:46+00:00","dateModified":"2023-11-23T15:01:31+00:00","description":"Massgeschneiderte L\u00f6sungen f\u00fcr die Beleuchtung Ihres Innenraums, Raum- und Lichtanalyse, Auswahl von Trendleuchten, Beleuchtung","breadcrumb":{"@id":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ekkla.ch\/de\/unsere-dienstleistungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ekkla.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Unsere Dienstleistungen"}]},{"@type":"WebSite","@id":"https:\/\/ekkla.ch\/#website","url":"https:\/\/ekkla.ch\/","name":"Ekkla","description":"Der Onlineshop f\u00fcr Beleuchtung","publisher":{"@id":"https:\/\/ekkla.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ekkla.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ekkla.ch\/#organization","name":"Ekkla","url":"https:\/\/ekkla.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ekkla.ch\/#\/schema\/logo\/image\/","url":"http:\/\/ekkla.ch\/wp-content\/uploads\/2019\/07\/logo-1.svg","contentUrl":"http:\/\/ekkla.ch\/wp-content\/uploads\/2019\/07\/logo-1.svg","width":1,"height":1,"caption":"Ekkla"},"image":{"@id":"https:\/\/ekkla.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ekkla_light\/"]}]}},"_links":{"self":[{"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/pages\/9018"}],"collection":[{"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/comments?post=9018"}],"version-history":[{"count":0,"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/pages\/9018\/revisions"}],"wp:attachment":[{"href":"https:\/\/ekkla.ch\/de\/wp-json\/wp\/v2\/media?parent=9018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}